{"id":9974,"count":4,"description":"","link":"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/hockeyspieler\/","name":"Hockeyspieler","slug":"hockeyspieler","taxonomy":"category","parent":9956,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hockeyspieler Archives - Biography Tribune<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/hockeyspieler\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hockeyspieler Archives - Biography Tribune\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/hockeyspieler\/\" \/>\n<meta property=\"og:site_name\" content=\"Biography Tribune\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/hockeyspieler\/\",\"url\":\"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/hockeyspieler\/\",\"name\":\"Hockeyspieler Archives - Biography Tribune\",\"isPartOf\":{\"@id\":\"https:\/\/biographytribune.com\/de\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/hockeyspieler\/#breadcrumb\"},\"inLanguage\":\"de-DE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/hockeyspieler\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/biographytribune.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sportler\",\"item\":\"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hockeyspieler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/biographytribune.com\/de\/#website\",\"url\":\"https:\/\/biographytribune.com\/de\/\",\"name\":\"Biography Tribune\",\"description\":\"Wiki Of Famous Actors, Athletes, Businesspersons, Web Stars\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/biographytribune.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hockeyspieler Archives - Biography Tribune","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/hockeyspieler\/","og_locale":"de_DE","og_type":"article","og_title":"Hockeyspieler Archives - Biography Tribune","og_url":"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/hockeyspieler\/","og_site_name":"Biography Tribune","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/hockeyspieler\/","url":"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/hockeyspieler\/","name":"Hockeyspieler Archives - Biography Tribune","isPartOf":{"@id":"https:\/\/biographytribune.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/hockeyspieler\/#breadcrumb"},"inLanguage":"de-DE"},{"@type":"BreadcrumbList","@id":"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/hockeyspieler\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/biographytribune.com\/de\/"},{"@type":"ListItem","position":2,"name":"Sportler","item":"https:\/\/biographytribune.com\/de\/kategorie\/sportler\/"},{"@type":"ListItem","position":3,"name":"Hockeyspieler"}]},{"@type":"WebSite","@id":"https:\/\/biographytribune.com\/de\/#website","url":"https:\/\/biographytribune.com\/de\/","name":"Biography Tribune","description":"Wiki Of Famous Actors, Athletes, Businesspersons, Web Stars","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biographytribune.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/biographytribune.com\/de\/wp-json\/wp\/v2\/categories\/9974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biographytribune.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/biographytribune.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/biographytribune.com\/de\/wp-json\/wp\/v2\/categories\/9956"}],"wp:post_type":[{"href":"https:\/\/biographytribune.com\/de\/wp-json\/wp\/v2\/posts?categories=9974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}